{"id":4957,"date":"2025-01-12T16:27:51","date_gmt":"2025-01-12T13:27:51","guid":{"rendered":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13.jpeg"},"modified":"2025-01-12T16:27:51","modified_gmt":"2025-01-12T13:27:51","slug":"whatsapp-image-2025-01-11-at-11-04-13-2","status":"inherit","type":"attachment","link":"https:\/\/kartalhomes.com\/en\/whatsapp-image-2025-01-11-at-11-04-13-2\/","title":{"rendered":"WhatsApp Image 2025-01-11 at 11.04.13"},"author":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13.jpeg'><img width=\"300\" height=\"225\" src=\"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-300x225.jpeg 300w, https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-1024x768.jpeg 1024w, https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-768x576.jpeg 768w, https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-1536x1152.jpeg 1536w, https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1200,"file":"2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13.jpeg","sizes":{"medium":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-300x225.jpeg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-300x225.jpeg"},"large":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-1024x768.jpeg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-1024x768.jpeg"},"thumbnail":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-150x150.jpeg"},"medium_large":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-768x576.jpeg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-768x576.jpeg"},"1536x1536":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-1536x1152.jpeg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-1536x1152.jpeg"},"cargopress-jumbotron-slider-l":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-1600x600.jpeg","width":1600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-1600x600.jpeg"},"cargopress-jumbotron-slider-m":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-960x300.jpeg","width":960,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-960x300.jpeg"},"cargopress-jumbotron-slider-s":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-480x150.jpeg","width":480,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-480x150.jpeg"},"latest-posts":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-270x190.jpeg","width":270,"height":190,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-270x190.jpeg"},"pw-page-box":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-360x240.jpeg","width":360,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-360x240.jpeg"},"pw-inline":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-100x70.jpeg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-100x70.jpeg"},"pw-latest-news":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-360x204.jpeg","width":360,"height":204,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-360x204.jpeg"},"sow-carousel-default":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13-272x182.jpeg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13-272x182.jpeg"},"full":{"file":"WhatsApp-Image-2025-01-11-at-11.04.13.jpeg","width":1600,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/kartalhomes.com\/site\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-11-at-11.04.13.jpeg","_links":{"self":[{"href":"https:\/\/kartalhomes.com\/en\/wp-json\/wp\/v2\/media\/4957"}],"collection":[{"href":"https:\/\/kartalhomes.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/kartalhomes.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/kartalhomes.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kartalhomes.com\/en\/wp-json\/wp\/v2\/comments?post=4957"}]}}